{"id":1299016,"date":"2026-07-14T11:42:38","date_gmt":"2026-07-14T11:42:38","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"dubbelhjul-ka3046","status":"publish","type":"product","link":"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/","title":{"rendered":"Dubbelhjul"},"content":{"rendered":"<p>Ett robust dubbelhjulssystem utformat f\u00f6r att minska marktrycket och minimera hjulsp\u00e5r, vilket ger f\u00f6rb\u00e4ttrad stabilitet i sluttningar och \u00f6verl\u00e4gset grepp i leriga f\u00f6rh\u00e5llanden j\u00e4mf\u00f6rt med ett enkelhjulssystem.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ett robust dubbelhjulssystem utformat f\u00f6r att minska marktrycket och minimera hjulsp\u00e5r, vilket ger f\u00f6rb\u00e4ttrad stabilitet i sluttningar och \u00f6verl\u00e4gset grepp i leriga f\u00f6rh\u00e5llanden j\u00e4mf\u00f6rt med ett enkelhjulssystem.<\/p>\n","protected":false},"featured_media":555339,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52469],"product_tag":[],"class_list":{"0":"post-1299016","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tillbehor-for-robotgrasklippare","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dubbelhjul | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dubbelhjul\" \/>\n<meta property=\"og:description\" content=\"Ett robust dubbelhjulssystem utformat f\u00f6r att minska marktrycket och minimera hjulsp\u00e5r, vilket ger f\u00f6rb\u00e4ttrad stabilitet i sluttningar och \u00f6verl\u00e4gset grepp i leriga f\u00f6rh\u00e5llanden j\u00e4mf\u00f6rt med ett enkelhjulssystem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_88861a4baea889cabff5f6cb829a915c43d31a27.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/sv-se\\\/dubbelhjul-ka3046\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/sv-se\\\/dubbelhjul-ka3046\\\/\",\"name\":\"Dubbelhjul | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/sv-se\\\/dubbelhjul-ka3046\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/sv-se\\\/dubbelhjul-ka3046\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_88861a4baea889cabff5f6cb829a915c43d31a27.1980x.webp\",\"datePublished\":\"2026-07-14T11:42:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/sv-se\\\/dubbelhjul-ka3046\\\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/sv-se\\\/dubbelhjul-ka3046\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/sv-se\\\/dubbelhjul-ka3046\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_88861a4baea889cabff5f6cb829a915c43d31a27.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_88861a4baea889cabff5f6cb829a915c43d31a27.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/sv-se\\\/dubbelhjul-ka3046\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/sv-se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dubbelhjul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dubbelhjul | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"sv_SE","og_type":"article","og_title":"Dubbelhjul","og_description":"Ett robust dubbelhjulssystem utformat f\u00f6r att minska marktrycket och minimera hjulsp\u00e5r, vilket ger f\u00f6rb\u00e4ttrad stabilitet i sluttningar och \u00f6verl\u00e4gset grepp i leriga f\u00f6rh\u00e5llanden j\u00e4mf\u00f6rt med ett enkelhjulssystem.","og_url":"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_88861a4baea889cabff5f6cb829a915c43d31a27.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/","url":"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/","name":"Dubbelhjul | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_88861a4baea889cabff5f6cb829a915c43d31a27.1980x.webp","datePublished":"2026-07-14T11:42:38+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/"]}]},{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_88861a4baea889cabff5f6cb829a915c43d31a27.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_88861a4baea889cabff5f6cb829a915c43d31a27.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/sv-se\/dubbelhjul-ka3046\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/sv-se\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Dubbelhjul"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/sv-se\/wp-json\/wp\/v2\/product\/1299016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/sv-se\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/sv-se\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/sv-se\/wp-json\/wp\/v2\/media\/555339"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/sv-se\/wp-json\/wp\/v2\/media?parent=1299016"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/sv-se\/wp-json\/wp\/v2\/product_brand?post=1299016"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/sv-se\/wp-json\/wp\/v2\/product_cat?post=1299016"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/sv-se\/wp-json\/wp\/v2\/product_tag?post=1299016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}