{"id":1298826,"date":"2026-07-14T11:42:30","date_gmt":"2026-07-14T11:42:30","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"mulchmes-ka0008","status":"publish","type":"product","link":"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/","title":{"rendered":"Mulchmes"},"content":{"rendered":"<p>Een effici\u00ebnte en milieuvriendelijke manier om gemaaid gras fijn te hakselen voor natuurlijke bemesting van het gazon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Een effici\u00ebnte en milieuvriendelijke manier om gemaaid gras fijn te hakselen voor natuurlijke bemesting van het gazon.<\/p>\n","protected":false},"featured_media":551038,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52461],"product_tag":[],"class_list":{"0":"post-1298826","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-voor-robotmaaiers","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mulchmes | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mulchmes\" \/>\n<meta property=\"og:description\" content=\"Een effici\u00ebnte en milieuvriendelijke manier om gemaaid gras fijn te hakselen voor natuurlijke bemesting van het gazon.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b335c1e416df9b5ef38208ddce0cde88d75f621f.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-nl\\\/mulchmes-ka0008\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/nl-nl\\\/mulchmes-ka0008\\\/\",\"name\":\"Mulchmes | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-nl\\\/mulchmes-ka0008\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-nl\\\/mulchmes-ka0008\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_b335c1e416df9b5ef38208ddce0cde88d75f621f.1980x.webp\",\"datePublished\":\"2026-07-14T11:42:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-nl\\\/mulchmes-ka0008\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/nl-nl\\\/mulchmes-ka0008\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-nl\\\/mulchmes-ka0008\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_b335c1e416df9b5ef38208ddce0cde88d75f621f.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_b335c1e416df9b5ef38208ddce0cde88d75f621f.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-nl\\\/mulchmes-ka0008\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/nl-nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mulchmes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mulchmes | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"Mulchmes","og_description":"Een effici\u00ebnte en milieuvriendelijke manier om gemaaid gras fijn te hakselen voor natuurlijke bemesting van het gazon.","og_url":"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b335c1e416df9b5ef38208ddce0cde88d75f621f.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/","url":"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/","name":"Mulchmes | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b335c1e416df9b5ef38208ddce0cde88d75f621f.1980x.webp","datePublished":"2026-07-14T11:42:30+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b335c1e416df9b5ef38208ddce0cde88d75f621f.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b335c1e416df9b5ef38208ddce0cde88d75f621f.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/nl-nl\/mulchmes-ka0008\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/nl-nl\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Mulchmes"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/nl-nl\/wp-json\/wp\/v2\/product\/1298826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/nl-nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/nl-nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/nl-nl\/wp-json\/wp\/v2\/media\/551038"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/nl-nl\/wp-json\/wp\/v2\/media?parent=1298826"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/nl-nl\/wp-json\/wp\/v2\/product_brand?post=1298826"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/nl-nl\/wp-json\/wp\/v2\/product_cat?post=1298826"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/nl-nl\/wp-json\/wp\/v2\/product_tag?post=1298826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}