{"id":1297611,"date":"2026-07-14T11:41:26","date_gmt":"2026-07-14T11:41:26","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"messen-met-lange-levensduur-ka0017","status":"publish","type":"product","link":"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/","title":{"rendered":"Messen met lange levensduur"},"content":{"rendered":"<p>Past voor Kress <sup>RTKn<\/sup> KR16X, KR17X en KR233E\/KR236E met oude snijschijf*. Nieuw fabricageproces verbetert de slijtvastheid van het mes, <strong><em><u>speciaal voor commercieel gebruik.<\/u><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Past voor Kress RTKn KR16X, KR17X en KR233E\/KR236E met oude snijschijf*. Nieuw fabricageproces verbetert de slijtvastheid van het mes, speciaal voor commercieel gebruik.<\/p>\n","protected":false},"featured_media":411640,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52468],"product_tag":[],"class_list":{"0":"post-1297611","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-voor-robotmaaiers","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Messen met lange levensduur | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messen met lange levensduur\" \/>\n<meta property=\"og:description\" content=\"Past voor Kress RTKn KR16X, KR17X en KR233E\/KR236E met oude snijschijf*. Nieuw fabricageproces verbetert de slijtvastheid van het mes, speciaal voor commercieel gebruik.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b5b1e4066c0da797cfc091e95555834210720318.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-be\\\/messen-met-lange-levensduur-ka0017\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/nl-be\\\/messen-met-lange-levensduur-ka0017\\\/\",\"name\":\"Messen met lange levensduur | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-be\\\/messen-met-lange-levensduur-ka0017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-be\\\/messen-met-lange-levensduur-ka0017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_b5b1e4066c0da797cfc091e95555834210720318.1980x.webp\",\"datePublished\":\"2026-07-14T11:41:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-be\\\/messen-met-lange-levensduur-ka0017\\\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/nl-be\\\/messen-met-lange-levensduur-ka0017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-be\\\/messen-met-lange-levensduur-ka0017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_b5b1e4066c0da797cfc091e95555834210720318.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_b5b1e4066c0da797cfc091e95555834210720318.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/nl-be\\\/messen-met-lange-levensduur-ka0017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/nl-be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Messen met lange levensduur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-BE\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Messen met lange levensduur | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_BE","og_type":"article","og_title":"Messen met lange levensduur","og_description":"Past voor Kress RTKn KR16X, KR17X en KR233E\/KR236E met oude snijschijf*. Nieuw fabricageproces verbetert de slijtvastheid van het mes, speciaal voor commercieel gebruik.","og_url":"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b5b1e4066c0da797cfc091e95555834210720318.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/","url":"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/","name":"Messen met lange levensduur | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b5b1e4066c0da797cfc091e95555834210720318.1980x.webp","datePublished":"2026-07-14T11:41:26+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/"]}]},{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b5b1e4066c0da797cfc091e95555834210720318.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b5b1e4066c0da797cfc091e95555834210720318.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/nl-be\/messen-met-lange-levensduur-ka0017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/nl-be\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Messen met lange levensduur"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"nl-BE","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/nl-be\/wp-json\/wp\/v2\/product\/1297611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/nl-be\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/nl-be\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/nl-be\/wp-json\/wp\/v2\/media\/411640"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/nl-be\/wp-json\/wp\/v2\/media?parent=1297611"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/nl-be\/wp-json\/wp\/v2\/product_brand?post=1297611"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/nl-be\/wp-json\/wp\/v2\/product_cat?post=1297611"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/nl-be\/wp-json\/wp\/v2\/product_tag?post=1297611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}