{"id":1297672,"date":"2026-07-14T11:41:28","date_gmt":"2026-07-14T11:41:28","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"lama-di-lunga-durata-vite-nuova-ka0018","status":"publish","type":"product","link":"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/","title":{"rendered":"Lama di lunga durata (vite nuova)"},"content":{"rendered":"<p>Adatta a 236, nuovi KR236.2, KR236E.2 e KR236E.2 dopo la sostituzione della nuova testa di taglio nella confezione regalo KA0169. Il nuovo processo di produzione delle lame ne migliora la resistenza all&#8217;usura, <strong><em><u>soprattutto per l&#8217;uso commerciale<\/u><\/em><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adatta a 236, nuovi KR236.2, KR236E.2 e KR236E.2 dopo la sostituzione della nuova testa di taglio nella confezione regalo KA0169. Il nuovo processo di produzione delle lame ne migliora la resistenza all&#8217;usura, soprattutto per l&#8217;uso commerciale.<\/p>\n","protected":false},"featured_media":411688,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52477],"product_tag":[],"class_list":{"0":"post-1297672","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessori-per-falciatrici-robotiche","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lama di lunga durata (vite nuova) | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lama di lunga durata (vite nuova)\" \/>\n<meta property=\"og:description\" content=\"Adatta a 236, nuovi KR236.2, KR236E.2 e KR236E.2 dopo la sostituzione della nuova testa di taglio nella confezione regalo KA0169. Il nuovo processo di produzione delle lame ne migliora la resistenza all&#8217;usura, soprattutto per l&#8217;uso commerciale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/it-ch\\\/lama-di-lunga-durata-vite-nuova-ka0018\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/it-ch\\\/lama-di-lunga-durata-vite-nuova-ka0018\\\/\",\"name\":\"Lama di lunga durata (vite nuova) | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/it-ch\\\/lama-di-lunga-durata-vite-nuova-ka0018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/it-ch\\\/lama-di-lunga-durata-vite-nuova-ka0018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp\",\"datePublished\":\"2026-07-14T11:41:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/it-ch\\\/lama-di-lunga-durata-vite-nuova-ka0018\\\/#breadcrumb\"},\"inLanguage\":\"it-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/it-ch\\\/lama-di-lunga-durata-vite-nuova-ka0018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-CH\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/it-ch\\\/lama-di-lunga-durata-vite-nuova-ka0018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/it-ch\\\/lama-di-lunga-durata-vite-nuova-ka0018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/it-ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lama di lunga durata (vite nuova)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-CH\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lama di lunga durata (vite nuova) | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Lama di lunga durata (vite nuova)","og_description":"Adatta a 236, nuovi KR236.2, KR236E.2 e KR236E.2 dopo la sostituzione della nuova testa di taglio nella confezione regalo KA0169. Il nuovo processo di produzione delle lame ne migliora la resistenza all&#8217;usura, soprattutto per l&#8217;uso commerciale.","og_url":"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/","url":"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/","name":"Lama di lunga durata (vite nuova) | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp","datePublished":"2026-07-14T11:41:28+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/#breadcrumb"},"inLanguage":"it-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/"]}]},{"@type":"ImageObject","inLanguage":"it-CH","@id":"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/it-ch\/lama-di-lunga-durata-vite-nuova-ka0018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/it-ch\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Lama di lunga durata (vite nuova)"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-CH"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"it-CH","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/it-ch\/wp-json\/wp\/v2\/product\/1297672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/it-ch\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/it-ch\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/it-ch\/wp-json\/wp\/v2\/media\/411688"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/it-ch\/wp-json\/wp\/v2\/media?parent=1297672"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/it-ch\/wp-json\/wp\/v2\/product_brand?post=1297672"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/it-ch\/wp-json\/wp\/v2\/product_cat?post=1297672"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/it-ch\/wp-json\/wp\/v2\/product_tag?post=1297672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}