{"id":1292812,"date":"2026-07-14T11:37:50","date_gmt":"2026-07-14T11:37:50","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\/","title":{"rendered":"Tondeuse robotis\u00e9e Kress RTK\u207f de 2 000 m\u00b2 avec OAS (Obstacle Avoidance System)"},"content":{"rendered":"<p>Red\u00e9finissant la pr\u00e9cision dans l&#8217;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR172E.A offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&#8217;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Red\u00e9finissant la pr\u00e9cision dans l&#8217;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR172E.A offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&#8217;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9.<\/p>\n","protected":false},"featured_media":408232,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52402],"product_tag":[],"class_list":{"0":"post-1292812","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tondeuses-a-gazon-robotisees","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tondeuse robotis\u00e9e Kress RTK\u207f de 2 000 m\u00b2 avec OAS (Obstacle Avoidance System) | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tondeuse robotis\u00e9e Kress RTK\u207f de 2 000 m\u00b2 avec OAS (Obstacle Avoidance System)\" \/>\n<meta property=\"og:description\" content=\"Red\u00e9finissant la pr\u00e9cision dans l&#8217;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR172E.A offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&#8217;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk\u207f-de-2-000-m\u00b2-avec-oas-obstacle-avoidance-system-kr172e-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d82099ac5853b5f38b5315117a3dcde3067266c2.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\\\/\",\"name\":\"Tondeuse robotis\u00e9e Kress RTK\u207f de 2 000 m\u00b2 avec OAS (Obstacle Avoidance System) | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_d82099ac5853b5f38b5315117a3dcde3067266c2.1980x.webp\",\"datePublished\":\"2026-07-14T11:37:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\\\/#breadcrumb\"},\"inLanguage\":\"fr-LU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LU\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_d82099ac5853b5f38b5315117a3dcde3067266c2.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_d82099ac5853b5f38b5315117a3dcde3067266c2.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tondeuse robotis\u00e9e Kress RTK\u207f de 2 000 m\u00b2 avec OAS (Obstacle Avoidance System)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-LU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LU\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tondeuse robotis\u00e9e Kress RTK\u207f de 2 000 m\u00b2 avec OAS (Obstacle Avoidance System) | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Tondeuse robotis\u00e9e Kress RTK\u207f de 2 000 m\u00b2 avec OAS (Obstacle Avoidance System)","og_description":"Red\u00e9finissant la pr\u00e9cision dans l&#8217;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR172E.A offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&#8217;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9.","og_url":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk\u207f-de-2-000-m\u00b2-avec-oas-obstacle-avoidance-system-kr172e-a\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d82099ac5853b5f38b5315117a3dcde3067266c2.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\/","url":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\/","name":"Tondeuse robotis\u00e9e Kress RTK\u207f de 2 000 m\u00b2 avec OAS (Obstacle Avoidance System) | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d82099ac5853b5f38b5315117a3dcde3067266c2.1980x.webp","datePublished":"2026-07-14T11:37:50+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\/#breadcrumb"},"inLanguage":"fr-LU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\/"]}]},{"@type":"ImageObject","inLanguage":"fr-LU","@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d82099ac5853b5f38b5315117a3dcde3067266c2.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d82099ac5853b5f38b5315117a3dcde3067266c2.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-2-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr172e-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-lu\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Tondeuse robotis\u00e9e Kress RTK\u207f de 2 000 m\u00b2 avec OAS (Obstacle Avoidance System)"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-LU"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-LU","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product\/1292812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/media\/408232"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/media?parent=1292812"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product_brand?post=1292812"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product_cat?post=1292812"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product_tag?post=1292812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}