{"id":1291590,"date":"2026-07-14T11:37:01","date_gmt":"2026-07-14T11:37:01","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/","title":{"rendered":"La tondeuse robot Kress Mission Mega g\u00e8re des pelouses jusqu&#8217;\u00e0 4 400 m\u00b2 gr\u00e2ce au syst\u00e8me OAS (Obstacle Avoidance System)"},"content":{"rendered":"<p>Con\u00e7ue pour les pelouses \u00e9tendues, la Kress Mission Mega est \u00e9quip\u00e9e d&#8217;un double disque plus large et INTIVA couvre plus rapidement la zone \u00e0 tondre. Combinant efficacit\u00e9, intelligence et fiabilit\u00e9, elle \u00e9tablit un nouveau standard dans l&#8217;entretien des pelouses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con\u00e7ue pour les pelouses \u00e9tendues, la Kress Mission Mega est \u00e9quip\u00e9e d&#8217;un double disque plus large et INTIVA couvre plus rapidement la zone \u00e0 tondre. Combinant efficacit\u00e9, intelligence et fiabilit\u00e9, elle \u00e9tablit un nouveau standard dans l&#8217;entretien des pelouses.<\/p>\n","protected":false},"featured_media":407896,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52402],"product_tag":[],"class_list":{"0":"post-1291590","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tondeuses-a-gazon-robotisees","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La tondeuse robot Kress Mission Mega g\u00e8re des pelouses jusqu&#039;\u00e0 4 400 m\u00b2 gr\u00e2ce au syst\u00e8me OAS (Obstacle Avoidance System) | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La tondeuse robot Kress Mission Mega g\u00e8re des pelouses jusqu&#039;\u00e0 4 400 m\u00b2 gr\u00e2ce au syst\u00e8me OAS (Obstacle Avoidance System)\" \/>\n<meta property=\"og:description\" content=\"Con\u00e7ue pour les pelouses \u00e9tendues, la Kress Mission Mega est \u00e9quip\u00e9e d&#8217;un double disque plus large et INTIVA couvre plus rapidement la zone \u00e0 tondre. Combinant efficacit\u00e9, intelligence et fiabilit\u00e9, elle \u00e9tablit un nouveau standard dans l&#8217;entretien des pelouses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m\u00b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c822a9e606c39b1104c54ef9118fd503c3bbe16a.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\\\/\",\"name\":\"La tondeuse robot Kress Mission Mega g\u00e8re des pelouses jusqu'\u00e0 4 400 m\u00b2 gr\u00e2ce au syst\u00e8me OAS (Obstacle Avoidance System) | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_c822a9e606c39b1104c54ef9118fd503c3bbe16a.1980x.webp\",\"datePublished\":\"2026-07-14T11:37:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\\\/#breadcrumb\"},\"inLanguage\":\"fr-LU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LU\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_c822a9e606c39b1104c54ef9118fd503c3bbe16a.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_c822a9e606c39b1104c54ef9118fd503c3bbe16a.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La tondeuse robot Kress Mission Mega g\u00e8re des pelouses jusqu&#8217;\u00e0 4 400 m\u00b2 gr\u00e2ce au syst\u00e8me OAS (Obstacle Avoidance System)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-LU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LU\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La tondeuse robot Kress Mission Mega g\u00e8re des pelouses jusqu'\u00e0 4 400 m\u00b2 gr\u00e2ce au syst\u00e8me OAS (Obstacle Avoidance System) | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"La tondeuse robot Kress Mission Mega g\u00e8re des pelouses jusqu'\u00e0 4 400 m\u00b2 gr\u00e2ce au syst\u00e8me OAS (Obstacle Avoidance System)","og_description":"Con\u00e7ue pour les pelouses \u00e9tendues, la Kress Mission Mega est \u00e9quip\u00e9e d&#8217;un double disque plus large et INTIVA couvre plus rapidement la zone \u00e0 tondre. Combinant efficacit\u00e9, intelligence et fiabilit\u00e9, elle \u00e9tablit un nouveau standard dans l&#8217;entretien des pelouses.","og_url":"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m\u00b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c822a9e606c39b1104c54ef9118fd503c3bbe16a.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/","url":"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/","name":"La tondeuse robot Kress Mission Mega g\u00e8re des pelouses jusqu'\u00e0 4 400 m\u00b2 gr\u00e2ce au syst\u00e8me OAS (Obstacle Avoidance System) | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c822a9e606c39b1104c54ef9118fd503c3bbe16a.1980x.webp","datePublished":"2026-07-14T11:37:01+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/#breadcrumb"},"inLanguage":"fr-LU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/"]}]},{"@type":"ImageObject","inLanguage":"fr-LU","@id":"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c822a9e606c39b1104c54ef9118fd503c3bbe16a.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c822a9e606c39b1104c54ef9118fd503c3bbe16a.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-lu\/la-tondeuse-robot-kress-mission-mega-gere-des-pelouses-jusqua-4-400-m%c2%b2-grace-au-systeme-oas-obstacle-avoidance-system-kr133e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-lu\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"La tondeuse robot Kress Mission Mega g\u00e8re des pelouses jusqu&#8217;\u00e0 4 400 m\u00b2 gr\u00e2ce au syst\u00e8me OAS (Obstacle Avoidance System)"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-LU"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-LU","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product\/1291590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/media\/407896"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/media?parent=1291590"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product_brand?post=1291590"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product_cat?post=1291590"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product_tag?post=1291590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}