{"id":1291356,"date":"2026-07-14T11:36:57","date_gmt":"2026-07-14T11:36:57","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\/","title":{"rendered":"Tondeuse robotis\u00e9e Kress RTK\u207f de 8 000 m\u00b2 avec OAS (Obstacle Avoidance System)"},"content":{"rendered":"<p>Red\u00e9finissant la pr\u00e9cision dans l&#8217;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR230E offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&#8217;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9. \u00c9quip\u00e9e de lames \u00e0 double couche et d&#8217;un syst\u00e8me d&#8217;\u00e9vitement des obstacles, la KR230E fonctionne efficacement dans toutes les conditions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Red\u00e9finissant la pr\u00e9cision dans l&#8217;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR230E offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&#8217;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9. \u00c9quip\u00e9e de lames \u00e0 double couche et d&#8217;un syst\u00e8me d&#8217;\u00e9vitement des obstacles, la KR230E fonctionne efficacement dans toutes les conditions.<\/p>\n","protected":false},"featured_media":407752,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52402],"product_tag":[],"class_list":["post-1291356","product","type-product","status-publish","has-post-thumbnail","product_cat-tondeuses-a-gazon-robotisees","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tondeuse robotis\u00e9e Kress RTK\u207f de 8 000 m\u00b2 avec OAS (Obstacle Avoidance System) | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tondeuse robotis\u00e9e Kress RTK\u207f de 8 000 m\u00b2 avec OAS (Obstacle Avoidance System)\" \/>\n<meta property=\"og:description\" content=\"Red\u00e9finissant la pr\u00e9cision dans l&#8217;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR230E offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&#8217;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9. \u00c9quip\u00e9e de lames \u00e0 double couche et d&#8217;un syst\u00e8me d&#8217;\u00e9vitement des obstacles, la KR230E fonctionne efficacement dans toutes les conditions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk\u207f-de-8-000-m\u00b2-avec-oas-obstacle-avoidance-system-kr230e\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_f744c4f88f416f74eeccb58398f1f7667b3515d0.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\\\/\",\"name\":\"Tondeuse robotis\u00e9e Kress RTK\u207f de 8 000 m\u00b2 avec OAS (Obstacle Avoidance System) | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_f744c4f88f416f74eeccb58398f1f7667b3515d0.1980x.webp\",\"datePublished\":\"2026-07-14T11:36:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\\\/#breadcrumb\"},\"inLanguage\":\"fr-LU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LU\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_f744c4f88f416f74eeccb58398f1f7667b3515d0.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_f744c4f88f416f74eeccb58398f1f7667b3515d0.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-lu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tondeuse robotis\u00e9e Kress RTK\u207f de 8 000 m\u00b2 avec OAS (Obstacle Avoidance System)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-LU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-LU\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tondeuse robotis\u00e9e Kress RTK\u207f de 8 000 m\u00b2 avec OAS (Obstacle Avoidance System) | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Tondeuse robotis\u00e9e Kress RTK\u207f de 8 000 m\u00b2 avec OAS (Obstacle Avoidance System)","og_description":"Red\u00e9finissant la pr\u00e9cision dans l&#8217;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR230E offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&#8217;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9. \u00c9quip\u00e9e de lames \u00e0 double couche et d&#8217;un syst\u00e8me d&#8217;\u00e9vitement des obstacles, la KR230E fonctionne efficacement dans toutes les conditions.","og_url":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk\u207f-de-8-000-m\u00b2-avec-oas-obstacle-avoidance-system-kr230e\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_f744c4f88f416f74eeccb58398f1f7667b3515d0.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\/","url":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\/","name":"Tondeuse robotis\u00e9e Kress RTK\u207f de 8 000 m\u00b2 avec OAS (Obstacle Avoidance System) | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_f744c4f88f416f74eeccb58398f1f7667b3515d0.1980x.webp","datePublished":"2026-07-14T11:36:57+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\/#breadcrumb"},"inLanguage":"fr-LU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\/"]}]},{"@type":"ImageObject","inLanguage":"fr-LU","@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_f744c4f88f416f74eeccb58398f1f7667b3515d0.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_f744c4f88f416f74eeccb58398f1f7667b3515d0.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-lu\/tondeuse-robotisee-kress-rtk%e2%81%bf-de-8-000-m%c2%b2-avec-oas-obstacle-avoidance-system-kr230e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-lu\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Tondeuse robotis\u00e9e Kress RTK\u207f de 8 000 m\u00b2 avec OAS (Obstacle Avoidance System)"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-LU"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-LU","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product\/1291356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/media\/407752"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/media?parent=1291356"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product_brand?post=1291356"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product_cat?post=1291356"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-lu\/wp-json\/wp\/v2\/product_tag?post=1291356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}