{"id":1298201,"date":"2026-07-14T11:41:53","date_gmt":"2026-07-14T11:41:53","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\/","title":{"rendered":"Kress EyePilot\u00ae RTK\u207f 700 m\u00b2 robot tondeuse avec ZeroTrim"},"content":{"rendered":"<p>Offrant une qualit\u00e9 de tonte digne des plus beaux parcours, le Kress EyePilot\u00ae RTK\u207f KR260E combine le positionnement satellite RTK\u207f \u00e0 une perception par vision pour assurer une navigation stable et ultra pr\u00e9cise dans tous les environnements de jardin, sans mat\u00e9riel additionnel.<\/p>\n<p>La correction RTK\u207f est transmise par voie a\u00e9rienne et renforc\u00e9e par une architecture de positionnement redondante, permettant au robot de maintenir une pr\u00e9cision optimale m\u00eame lorsque le signal satellite est d\u00e9grad\u00e9.<\/p>\n<p>Le syst\u00e8me de coupe ZeroTrim assure une finition nette et pr\u00e9cise des bordures, r\u00e9duisant fortement le besoin de retouches manuelles. Les sch\u00e9mas de tonte peuvent \u00eatre configur\u00e9s pour obtenir des bandes structur\u00e9es ou un rendu plus naturel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offrant une qualit\u00e9 de tonte digne des plus beaux parcours, le Kress EyePilot\u00ae RTK\u207f KR260E combine le positionnement satellite RTK\u207f \u00e0 une perception par vision pour assurer une navigation stable et ultra pr\u00e9cise dans tous les environnements de jardin, sans mat\u00e9riel additionnel. La correction RTK\u207f est transmise par voie a\u00e9rienne et renforc\u00e9e par une architecture [&hellip;]<\/p>\n","protected":false},"featured_media":522440,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52383],"product_tag":[],"class_list":["post-1298201","product","type-product","status-publish","has-post-thumbnail","product_cat-tondeuses-a-gazon-robotisees","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kress EyePilot\u00ae RTK\u207f 700 m\u00b2 robot tondeuse avec ZeroTrim | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kress EyePilot\u00ae RTK\u207f 700 m\u00b2 robot tondeuse avec ZeroTrim\" \/>\n<meta property=\"og:description\" content=\"Offrant une qualit\u00e9 de tonte digne des plus beaux parcours, le Kress EyePilot\u00ae RTK\u207f KR260E combine le positionnement satellite RTK\u207f \u00e0 une perception par vision pour assurer une navigation stable et ultra pr\u00e9cise dans tous les environnements de jardin, sans mat\u00e9riel additionnel. La correction RTK\u207f est transmise par voie a\u00e9rienne et renforc\u00e9e par une architecture [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk\u207f-700-m\u00b2-robot-tondeuse-avec-zerotrim-kr260e\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\\\/\",\"name\":\"Kress EyePilot\u00ae RTK\u207f 700 m\u00b2 robot tondeuse avec ZeroTrim | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp\",\"datePublished\":\"2026-07-14T11:41:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kress EyePilot\u00ae RTK\u207f 700 m\u00b2 robot tondeuse avec ZeroTrim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kress EyePilot\u00ae RTK\u207f 700 m\u00b2 robot tondeuse avec ZeroTrim | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Kress EyePilot\u00ae RTK\u207f 700 m\u00b2 robot tondeuse avec ZeroTrim","og_description":"Offrant une qualit\u00e9 de tonte digne des plus beaux parcours, le Kress EyePilot\u00ae RTK\u207f KR260E combine le positionnement satellite RTK\u207f \u00e0 une perception par vision pour assurer une navigation stable et ultra pr\u00e9cise dans tous les environnements de jardin, sans mat\u00e9riel additionnel. La correction RTK\u207f est transmise par voie a\u00e9rienne et renforc\u00e9e par une architecture [&hellip;]","og_url":"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk\u207f-700-m\u00b2-robot-tondeuse-avec-zerotrim-kr260e\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\/","url":"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\/","name":"Kress EyePilot\u00ae RTK\u207f 700 m\u00b2 robot tondeuse avec ZeroTrim | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp","datePublished":"2026-07-14T11:41:53+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-fr\/kress-eyepilot-rtk%e2%81%bf-700-m%c2%b2-robot-tondeuse-avec-zerotrim-kr260e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Kress EyePilot\u00ae RTK\u207f 700 m\u00b2 robot tondeuse avec ZeroTrim"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-fr\/wp-json\/wp\/v2\/product\/1298201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-fr\/wp-json\/wp\/v2\/media\/522440"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-fr\/wp-json\/wp\/v2\/media?parent=1298201"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-fr\/wp-json\/wp\/v2\/product_brand?post=1298201"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-fr\/wp-json\/wp\/v2\/product_cat?post=1298201"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-fr\/wp-json\/wp\/v2\/product_tag?post=1298201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}