{"id":1298597,"date":"2026-07-14T11:42:14","date_gmt":"2026-07-14T11:42:14","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\/","title":{"rendered":"Tondeuse robotis\u00e9e Kress EyePilot\u00ae 4\u00d74 RTK\u207f 5000 m\u00b2"},"content":{"rendered":"<p>Con\u00e7u pour les terrains difficiles, le Kress EyePilot\u00ae 4\u00d74 RTK\u207f KR285E combine le positionnement satellite RTK\u207f avec une perception visuelle et un v\u00e9ritable syst\u00e8me \u00e0 quatre roues motrices pour offrir une navigation pr\u00e9cise et stable sur des terrains complexes, sans mat\u00e9riel suppl\u00e9mentaire. Une transmission \u00e0 quatre moteurs avec contr\u00f4le du couple en temps r\u00e9el maintient la traction et la direction sur des pentes pouvant atteindre 84 % (\u224840\u00b0), tandis que les essieux ind\u00e9pendants et la carrosserie articul\u00e9e maintiennent les quatre roues au sol et assurent un plan de coupe constant sur les terrains accident\u00e9s. La direction des roues avant permet des virages en douceur sans endommager le gazon, tandis que la garde au sol verticale de 6 cm permet \u00e0 la tondeuse de franchir les rebords sur\u00e9lev\u00e9s et les transitions en toute confiance. La correction RTK\u207f est transmise par voie hertzienne et prise en charge par une architecture de positionnement redondante pour une pr\u00e9cision fiable, m\u00eame lorsque les signaux satellites sont d\u00e9grad\u00e9s. La connectivit\u00e9 via Wi-Fi ou 4G int\u00e9gr\u00e9e garantit un fonctionnement continu, sans frais suppl\u00e9mentaires : la carte SIM et le service de donn\u00e9es sont inclus d\u00e8s le d\u00e9part.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con\u00e7u pour les terrains difficiles, le Kress EyePilot\u00ae 4\u00d74 RTK\u207f KR285E combine le positionnement satellite RTK\u207f avec une perception visuelle et un v\u00e9ritable syst\u00e8me \u00e0 quatre roues motrices pour offrir une navigation pr\u00e9cise et stable sur des terrains complexes, sans mat\u00e9riel suppl\u00e9mentaire. Une transmission \u00e0 quatre moteurs avec contr\u00f4le du couple en temps r\u00e9el maintient [&hellip;]<\/p>\n","protected":false},"featured_media":522570,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52389],"product_tag":[],"class_list":{"0":"post-1298597","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tondeuses-a-gazon-robotisees","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tondeuse robotis\u00e9e Kress EyePilot\u00ae 4\u00d74 RTK\u207f 5000 m\u00b2 | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tondeuse robotis\u00e9e Kress EyePilot\u00ae 4\u00d74 RTK\u207f 5000 m\u00b2\" \/>\n<meta property=\"og:description\" content=\"Con\u00e7u pour les terrains difficiles, le Kress EyePilot\u00ae 4\u00d74 RTK\u207f KR285E combine le positionnement satellite RTK\u207f avec une perception visuelle et un v\u00e9ritable syst\u00e8me \u00e0 quatre roues motrices pour offrir une navigation pr\u00e9cise et stable sur des terrains complexes, sans mat\u00e9riel suppl\u00e9mentaire. Une transmission \u00e0 quatre moteurs avec contr\u00f4le du couple en temps r\u00e9el maintient [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk\u207f-5000-m\u00b2-kr285e\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b395b2651412d1cfe66cc6d6ec6e537e3ec5938.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\\\/\",\"name\":\"Tondeuse robotis\u00e9e Kress EyePilot\u00ae 4\u00d74 RTK\u207f 5000 m\u00b2 | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_8b395b2651412d1cfe66cc6d6ec6e537e3ec5938.1980x.webp\",\"datePublished\":\"2026-07-14T11:42:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_8b395b2651412d1cfe66cc6d6ec6e537e3ec5938.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_8b395b2651412d1cfe66cc6d6ec6e537e3ec5938.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tondeuse robotis\u00e9e Kress EyePilot\u00ae 4\u00d74 RTK\u207f 5000 m\u00b2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tondeuse robotis\u00e9e Kress EyePilot\u00ae 4\u00d74 RTK\u207f 5000 m\u00b2 | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"Tondeuse robotis\u00e9e Kress EyePilot\u00ae 4\u00d74 RTK\u207f 5000 m\u00b2","og_description":"Con\u00e7u pour les terrains difficiles, le Kress EyePilot\u00ae 4\u00d74 RTK\u207f KR285E combine le positionnement satellite RTK\u207f avec une perception visuelle et un v\u00e9ritable syst\u00e8me \u00e0 quatre roues motrices pour offrir une navigation pr\u00e9cise et stable sur des terrains complexes, sans mat\u00e9riel suppl\u00e9mentaire. Une transmission \u00e0 quatre moteurs avec contr\u00f4le du couple en temps r\u00e9el maintient [&hellip;]","og_url":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk\u207f-5000-m\u00b2-kr285e\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b395b2651412d1cfe66cc6d6ec6e537e3ec5938.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\/","url":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\/","name":"Tondeuse robotis\u00e9e Kress EyePilot\u00ae 4\u00d74 RTK\u207f 5000 m\u00b2 | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b395b2651412d1cfe66cc6d6ec6e537e3ec5938.1980x.webp","datePublished":"2026-07-14T11:42:14+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b395b2651412d1cfe66cc6d6ec6e537e3ec5938.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b395b2651412d1cfe66cc6d6ec6e537e3ec5938.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-eyepilot-4x4-rtk%e2%81%bf-5000-m%c2%b2-kr285e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-ca\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Tondeuse robotis\u00e9e Kress EyePilot\u00ae 4\u00d74 RTK\u207f 5000 m\u00b2"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product\/1298597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media\/522570"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=1298597"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_brand?post=1298597"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_cat?post=1298597"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_tag?post=1298597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}