{"id":1297661,"date":"2026-07-14T11:41:28","date_gmt":"2026-07-14T11:41:28","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"lame-longue-duree-nouvelle-vis-ka0018","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-ca\/lame-longue-duree-nouvelle-vis-ka0018\/","title":{"rendered":"Lame longue dur\u00e9e (nouvelle vis)"},"content":{"rendered":"<p>Adapter 236, nouveau KR236.2, KR236E.2 et KR236E.2 apr\u00e8s avoir remplac\u00e9 le nouveau porte-outil dans l&#8217;emballage cadeau KA0169. Le nouveau processus de fabrication de la lame am\u00e9liore la r\u00e9sistance \u00e0 l&rsquo;usure de la lame, <strong><em><u>sp\u00e9cialement pour un usage commercial<\/u><\/em><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adapter 236, nouveau KR236.2, KR236E.2 et KR236E.2 apr\u00e8s avoir remplac\u00e9 le nouveau porte-outil dans l&#8217;emballage cadeau KA0169. Le nouveau processus de fabrication de la lame am\u00e9liore la r\u00e9sistance \u00e0 l&rsquo;usure de la lame, sp\u00e9cialement pour un usage commercial.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52466],"product_tag":[],"class_list":{"0":"post-1297661","1":"product","2":"type-product","3":"status-publish","5":"product_cat-accessoires-pour-tondeuses-robotisees","7":"first","8":"instock","9":"shipping-taxable","10":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lame longue dur\u00e9e (nouvelle vis) | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lame longue dur\u00e9e (nouvelle vis)\" \/>\n<meta property=\"og:description\" content=\"Adapter 236, nouveau KR236.2, KR236E.2 et KR236E.2 apr\u00e8s avoir remplac\u00e9 le nouveau porte-outil dans l&#8217;emballage cadeau KA0169. Le nouveau processus de fabrication de la lame am\u00e9liore la r\u00e9sistance \u00e0 l&rsquo;usure de la lame, sp\u00e9cialement pour un usage commercial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-ca\/lame-longue-duree-nouvelle-vis-ka0018\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/lame-longue-duree-nouvelle-vis-ka0018\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/lame-longue-duree-nouvelle-vis-ka0018\\\/\",\"name\":\"Lame longue dur\u00e9e (nouvelle vis) | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"datePublished\":\"2026-07-14T11:41:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/lame-longue-duree-nouvelle-vis-ka0018\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/lame-longue-duree-nouvelle-vis-ka0018\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/lame-longue-duree-nouvelle-vis-ka0018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lame longue dur\u00e9e (nouvelle vis)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lame longue dur\u00e9e (nouvelle vis) | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"Lame longue dur\u00e9e (nouvelle vis)","og_description":"Adapter 236, nouveau KR236.2, KR236E.2 et KR236E.2 apr\u00e8s avoir remplac\u00e9 le nouveau porte-outil dans l&#8217;emballage cadeau KA0169. Le nouveau processus de fabrication de la lame am\u00e9liore la r\u00e9sistance \u00e0 l&rsquo;usure de la lame, sp\u00e9cialement pour un usage commercial.","og_url":"https:\/\/www.kress.com\/fr-ca\/lame-longue-duree-nouvelle-vis-ka0018\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_b0d3a05aba21674c20d4ddd0e90891a3ee8af317.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-ca\/lame-longue-duree-nouvelle-vis-ka0018\/","url":"https:\/\/www.kress.com\/fr-ca\/lame-longue-duree-nouvelle-vis-ka0018\/","name":"Lame longue dur\u00e9e (nouvelle vis) | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"datePublished":"2026-07-14T11:41:28+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-ca\/lame-longue-duree-nouvelle-vis-ka0018\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-ca\/lame-longue-duree-nouvelle-vis-ka0018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-ca\/lame-longue-duree-nouvelle-vis-ka0018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-ca\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Lame longue dur\u00e9e (nouvelle vis)"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product\/1297661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=1297661"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_brand?post=1297661"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_cat?post=1297661"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_tag?post=1297661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}