{"id":1295113,"date":"2026-07-14T11:39:24","date_gmt":"2026-07-14T11:39:24","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"double-bandouliere-kac131","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/","title":{"rendered":"Double bandouli\u00e8re"},"content":{"rendered":"<p>Compatible avec : KC111\/KC170<\/p>\n<p>Le harnais double de base permet de r\u00e9partir la charge des mains sur les \u00e9paules de l&rsquo;utilisateur. Un coussin est inclus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compatible avec : KC111\/KC170 Le harnais double de base permet de r\u00e9partir la charge des mains sur les \u00e9paules de l&rsquo;utilisateur. Un coussin est inclus.<\/p>\n","protected":false},"featured_media":410008,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52596],"product_tag":[],"class_list":{"0":"post-1295113","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-pour-coupe-herbe","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Double bandouli\u00e8re | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Double bandouli\u00e8re\" \/>\n<meta property=\"og:description\" content=\"Compatible avec : KC111\/KC170 Le harnais double de base permet de r\u00e9partir la charge des mains sur les \u00e9paules de l&rsquo;utilisateur. Un coussin est inclus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d7b853cb6dfd11b005595921214293b42b3f7066.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/double-bandouliere-kac131\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/double-bandouliere-kac131\\\/\",\"name\":\"Double bandouli\u00e8re | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/double-bandouliere-kac131\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/double-bandouliere-kac131\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_d7b853cb6dfd11b005595921214293b42b3f7066.1980x.webp\",\"datePublished\":\"2026-07-14T11:39:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/double-bandouliere-kac131\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/double-bandouliere-kac131\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/double-bandouliere-kac131\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_d7b853cb6dfd11b005595921214293b42b3f7066.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_d7b853cb6dfd11b005595921214293b42b3f7066.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/double-bandouliere-kac131\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Double bandouli\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Double bandouli\u00e8re | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"Double bandouli\u00e8re","og_description":"Compatible avec : KC111\/KC170 Le harnais double de base permet de r\u00e9partir la charge des mains sur les \u00e9paules de l&rsquo;utilisateur. Un coussin est inclus.","og_url":"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d7b853cb6dfd11b005595921214293b42b3f7066.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/","url":"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/","name":"Double bandouli\u00e8re | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d7b853cb6dfd11b005595921214293b42b3f7066.1980x.webp","datePublished":"2026-07-14T11:39:24+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d7b853cb6dfd11b005595921214293b42b3f7066.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_d7b853cb6dfd11b005595921214293b42b3f7066.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-ca\/double-bandouliere-kac131\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-ca\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Double bandouli\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product\/1295113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media\/410008"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=1295113"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_brand?post=1295113"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_cat?post=1295113"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_tag?post=1295113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}