{"id":1294541,"date":"2026-07-14T11:39:02","date_gmt":"2026-07-14T11:39:02","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"station-electrique-portable-de-qualite-professionnelle-kac877e","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/","title":{"rendered":"Station \u00e9lectrique portable de qualit\u00e9 professionnelle"},"content":{"rendered":"<p>Ce chargeur DC-DC CyberSytem de 8 minutes fournit l&rsquo;\u00e9nergie n\u00e9cessaire pour charger n&rsquo;importe quel CyberPack Kress 60 V ou Kress 60 V pendant toute une journ\u00e9e. Rechargez-le apr\u00e8s le travail dans votre atelier ou votre garage et n&rsquo;ayez plus \u00e0 d\u00e9penser de l&rsquo;argent en carburant !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce chargeur DC-DC CyberSytem de 8 minutes fournit l&rsquo;\u00e9nergie n\u00e9cessaire pour charger n&rsquo;importe quel CyberPack Kress 60 V ou Kress 60 V pendant toute une journ\u00e9e. Rechargez-le apr\u00e8s le travail dans votre atelier ou votre garage et n&rsquo;ayez plus \u00e0 d\u00e9penser de l&rsquo;argent en carburant !<\/p>\n","protected":false},"featured_media":409552,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52492],"product_tag":[],"class_list":{"0":"post-1294541","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-60-v-commercial","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Station \u00e9lectrique portable de qualit\u00e9 professionnelle | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Station \u00e9lectrique portable de qualit\u00e9 professionnelle\" \/>\n<meta property=\"og:description\" content=\"Ce chargeur DC-DC CyberSytem de 8 minutes fournit l&rsquo;\u00e9nergie n\u00e9cessaire pour charger n&rsquo;importe quel CyberPack Kress 60 V ou Kress 60 V pendant toute une journ\u00e9e. Rechargez-le apr\u00e8s le travail dans votre atelier ou votre garage et n&rsquo;ayez plus \u00e0 d\u00e9penser de l&rsquo;argent en carburant !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b6733e79836435da9c8900d8c89414df613f1ec.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/station-electrique-portable-de-qualite-professionnelle-kac877e\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/station-electrique-portable-de-qualite-professionnelle-kac877e\\\/\",\"name\":\"Station \u00e9lectrique portable de qualit\u00e9 professionnelle | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/station-electrique-portable-de-qualite-professionnelle-kac877e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/station-electrique-portable-de-qualite-professionnelle-kac877e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_4b6733e79836435da9c8900d8c89414df613f1ec.1980x.webp\",\"datePublished\":\"2026-07-14T11:39:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/station-electrique-portable-de-qualite-professionnelle-kac877e\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/station-electrique-portable-de-qualite-professionnelle-kac877e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/station-electrique-portable-de-qualite-professionnelle-kac877e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_4b6733e79836435da9c8900d8c89414df613f1ec.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_4b6733e79836435da9c8900d8c89414df613f1ec.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/station-electrique-portable-de-qualite-professionnelle-kac877e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Station \u00e9lectrique portable de qualit\u00e9 professionnelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Station \u00e9lectrique portable de qualit\u00e9 professionnelle | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"Station \u00e9lectrique portable de qualit\u00e9 professionnelle","og_description":"Ce chargeur DC-DC CyberSytem de 8 minutes fournit l&rsquo;\u00e9nergie n\u00e9cessaire pour charger n&rsquo;importe quel CyberPack Kress 60 V ou Kress 60 V pendant toute une journ\u00e9e. Rechargez-le apr\u00e8s le travail dans votre atelier ou votre garage et n&rsquo;ayez plus \u00e0 d\u00e9penser de l&rsquo;argent en carburant !","og_url":"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b6733e79836435da9c8900d8c89414df613f1ec.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/","url":"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/","name":"Station \u00e9lectrique portable de qualit\u00e9 professionnelle | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b6733e79836435da9c8900d8c89414df613f1ec.1980x.webp","datePublished":"2026-07-14T11:39:02+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b6733e79836435da9c8900d8c89414df613f1ec.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b6733e79836435da9c8900d8c89414df613f1ec.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-ca\/station-electrique-portable-de-qualite-professionnelle-kac877e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-ca\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Station \u00e9lectrique portable de qualit\u00e9 professionnelle"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product\/1294541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media\/409552"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=1294541"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_brand?post=1294541"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_cat?post=1294541"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_tag?post=1294541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}