{"id":1293501,"date":"2026-07-14T11:38:17","date_gmt":"2026-07-14T11:38:17","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"kress-geotrace-ka0210","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/","title":{"rendered":"Kress GeoTrace"},"content":{"rendered":"<p>Compatible avec : KR101E, KR120E, KR121E, KR122E, KR123E. <\/p>\n<p>Un bo\u00eetier 4G assure une connectivit\u00e9 constante pour un robot, permettant des mesures antivol, une localisation pr\u00e9cise et un suivi de l&rsquo;activit\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compatible avec : KR101E, KR120E, KR121E, KR122E, KR123E. Un bo\u00eetier 4G assure une connectivit\u00e9 constante pour un robot, permettant des mesures antivol, une localisation pr\u00e9cise et un suivi de l&rsquo;activit\u00e9.<\/p>\n","protected":false},"featured_media":409168,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52466],"product_tag":[],"class_list":{"0":"post-1293501","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-pour-tondeuses-robotisees","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kress GeoTrace | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kress GeoTrace\" \/>\n<meta property=\"og:description\" content=\"Compatible avec : KR101E, KR120E, KR121E, KR122E, KR123E. Un bo\u00eetier 4G assure une connectivit\u00e9 constante pour un robot, permettant des mesures antivol, une localisation pr\u00e9cise et un suivi de l&rsquo;activit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b430bc3d2c2389efc409a075c6a7a1d06d4fb1e.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/kress-geotrace-ka0210\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/kress-geotrace-ka0210\\\/\",\"name\":\"Kress GeoTrace | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/kress-geotrace-ka0210\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/kress-geotrace-ka0210\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_8b430bc3d2c2389efc409a075c6a7a1d06d4fb1e.1980x.webp\",\"datePublished\":\"2026-07-14T11:38:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/kress-geotrace-ka0210\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/kress-geotrace-ka0210\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/kress-geotrace-ka0210\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_8b430bc3d2c2389efc409a075c6a7a1d06d4fb1e.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_8b430bc3d2c2389efc409a075c6a7a1d06d4fb1e.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/kress-geotrace-ka0210\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kress GeoTrace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kress GeoTrace | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"Kress GeoTrace","og_description":"Compatible avec : KR101E, KR120E, KR121E, KR122E, KR123E. Un bo\u00eetier 4G assure une connectivit\u00e9 constante pour un robot, permettant des mesures antivol, une localisation pr\u00e9cise et un suivi de l&rsquo;activit\u00e9.","og_url":"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b430bc3d2c2389efc409a075c6a7a1d06d4fb1e.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/","url":"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/","name":"Kress GeoTrace | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b430bc3d2c2389efc409a075c6a7a1d06d4fb1e.1980x.webp","datePublished":"2026-07-14T11:38:17+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b430bc3d2c2389efc409a075c6a7a1d06d4fb1e.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_8b430bc3d2c2389efc409a075c6a7a1d06d4fb1e.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-ca\/kress-geotrace-ka0210\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-ca\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Kress GeoTrace"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product\/1293501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media\/409168"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=1293501"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_brand?post=1293501"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_cat?post=1293501"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_tag?post=1293501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}