{"id":1293293,"date":"2026-07-14T11:38:07","date_gmt":"2026-07-14T11:38:07","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/","title":{"rendered":"Tondeuse robotis\u00e9e Kress RTK\u207f 6 acres avec OAS (Obstacle Avoidance System), moteur am\u00e9lior\u00e9 et V-Wheel."},"content":{"rendered":"<p>Red\u00e9finissant la pr\u00e9cision dans l&rsquo;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR236S offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&rsquo;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9, et il a \u00e9galement am\u00e9lior\u00e9 le moteur de coupe et le moteur d&rsquo;entra\u00eenement, \u00e9quip\u00e9 d&rsquo;une roue en V qui am\u00e9liore l&rsquo;adh\u00e9rence au sol. \u00c9quip\u00e9e de lames \u00e0 double couche aiguis\u00e9es comme des rasoirs et d&rsquo;un syst\u00e8me d&rsquo;\u00e9vitement des obstacles, la KR236S fonctionne efficacement dans toutes les conditions. Sa technologie collaborative MAP\u2122 (Mowing Action Plan) permet une gestion sans faille de chaque complexit\u00e9 de gazon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Red\u00e9finissant la pr\u00e9cision dans l&rsquo;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR236S offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&rsquo;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9, et il a \u00e9galement am\u00e9lior\u00e9 le moteur de coupe et le moteur d&rsquo;entra\u00eenement, \u00e9quip\u00e9 d&rsquo;une roue en V qui am\u00e9liore l&rsquo;adh\u00e9rence [&hellip;]<\/p>\n","protected":false},"featured_media":409096,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52389],"product_tag":[],"class_list":["post-1293293","product","type-product","status-publish","has-post-thumbnail","product_cat-tondeuses-a-gazon-robotisees","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tondeuse robotis\u00e9e Kress RTK\u207f 6 acres avec OAS (Obstacle Avoidance System), moteur am\u00e9lior\u00e9 et V-Wheel. | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tondeuse robotis\u00e9e Kress RTK\u207f 6 acres avec OAS (Obstacle Avoidance System), moteur am\u00e9lior\u00e9 et V-Wheel.\" \/>\n<meta property=\"og:description\" content=\"Red\u00e9finissant la pr\u00e9cision dans l&rsquo;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR236S offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&rsquo;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9, et il a \u00e9galement am\u00e9lior\u00e9 le moteur de coupe et le moteur d&rsquo;entra\u00eenement, \u00e9quip\u00e9 d&rsquo;une roue en V qui am\u00e9liore l&rsquo;adh\u00e9rence [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk\u207f-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_aa1f766f53a8b6ef4779d4da6cfe05b23c17d393.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\\\/\",\"name\":\"Tondeuse robotis\u00e9e Kress RTK\u207f 6 acres avec OAS (Obstacle Avoidance System), moteur am\u00e9lior\u00e9 et V-Wheel. | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_aa1f766f53a8b6ef4779d4da6cfe05b23c17d393.1980x.webp\",\"datePublished\":\"2026-07-14T11:38:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_aa1f766f53a8b6ef4779d4da6cfe05b23c17d393.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_aa1f766f53a8b6ef4779d4da6cfe05b23c17d393.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tondeuse robotis\u00e9e Kress RTK\u207f 6 acres avec OAS (Obstacle Avoidance System), moteur am\u00e9lior\u00e9 et V-Wheel.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tondeuse robotis\u00e9e Kress RTK\u207f 6 acres avec OAS (Obstacle Avoidance System), moteur am\u00e9lior\u00e9 et V-Wheel. | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_CA","og_type":"article","og_title":"Tondeuse robotis\u00e9e Kress RTK\u207f 6 acres avec OAS (Obstacle Avoidance System), moteur am\u00e9lior\u00e9 et V-Wheel.","og_description":"Red\u00e9finissant la pr\u00e9cision dans l&rsquo;entretien des pelouses gr\u00e2ce \u00e0 la technologie Kress RTK\u207f, le robot tondeuse KR236S offre une pr\u00e9cision au centim\u00e8tre pr\u00e8s, guid\u00e9e par satellite, sans n\u00e9cessiter d&rsquo;antennes fixes sp\u00e9cifiques \u00e0 la propri\u00e9t\u00e9, et il a \u00e9galement am\u00e9lior\u00e9 le moteur de coupe et le moteur d&rsquo;entra\u00eenement, \u00e9quip\u00e9 d&rsquo;une roue en V qui am\u00e9liore l&rsquo;adh\u00e9rence [&hellip;]","og_url":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk\u207f-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_aa1f766f53a8b6ef4779d4da6cfe05b23c17d393.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/","url":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/","name":"Tondeuse robotis\u00e9e Kress RTK\u207f 6 acres avec OAS (Obstacle Avoidance System), moteur am\u00e9lior\u00e9 et V-Wheel. | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_aa1f766f53a8b6ef4779d4da6cfe05b23c17d393.1980x.webp","datePublished":"2026-07-14T11:38:07+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_aa1f766f53a8b6ef4779d4da6cfe05b23c17d393.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_aa1f766f53a8b6ef4779d4da6cfe05b23c17d393.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-ca\/tondeuse-robotisee-kress-rtk%e2%81%bf-6-acres-avec-oas-obstacle-avoidance-system-moteur-ameliore-et-v-wheel-kr236s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-ca\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Tondeuse robotis\u00e9e Kress RTK\u207f 6 acres avec OAS (Obstacle Avoidance System), moteur am\u00e9lior\u00e9 et V-Wheel."}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product\/1293293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media\/409096"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=1293293"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_brand?post=1293293"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_cat?post=1293293"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-ca\/wp-json\/wp\/v2\/product_tag?post=1293293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}