{"id":1298988,"date":"2026-07-14T11:42:37","date_gmt":"2026-07-14T11:42:37","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"support-pour-telephone-ka3027","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/","title":{"rendered":"Support pour t\u00e9l\u00e9phone"},"content":{"rendered":"<p>Un accessoire pratique et s\u00fbr qui maintient votre t\u00e9l\u00e9phone en place pendant la cartographie, ce qui facilite la visualisation de l&rsquo;itin\u00e9raire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un accessoire pratique et s\u00fbr qui maintient votre t\u00e9l\u00e9phone en place pendant la cartographie, ce qui facilite la visualisation de l&rsquo;itin\u00e9raire.<\/p>\n","protected":false},"featured_media":555313,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52467],"product_tag":[],"class_list":{"0":"post-1298988","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-pour-tondeuses-robotisees","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Support pour t\u00e9l\u00e9phone | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Support pour t\u00e9l\u00e9phone\" \/>\n<meta property=\"og:description\" content=\"Un accessoire pratique et s\u00fbr qui maintient votre t\u00e9l\u00e9phone en place pendant la cartographie, ce qui facilite la visualisation de l&rsquo;itin\u00e9raire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_9a3fc8cdb221c84ad6729414bb073c1b9665d977.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/support-pour-telephone-ka3027\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/support-pour-telephone-ka3027\\\/\",\"name\":\"Support pour t\u00e9l\u00e9phone | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/support-pour-telephone-ka3027\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/support-pour-telephone-ka3027\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_9a3fc8cdb221c84ad6729414bb073c1b9665d977.1980x.webp\",\"datePublished\":\"2026-07-14T11:42:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/support-pour-telephone-ka3027\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/support-pour-telephone-ka3027\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/support-pour-telephone-ka3027\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_9a3fc8cdb221c84ad6729414bb073c1b9665d977.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_9a3fc8cdb221c84ad6729414bb073c1b9665d977.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/support-pour-telephone-ka3027\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Support pour t\u00e9l\u00e9phone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Support pour t\u00e9l\u00e9phone | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Support pour t\u00e9l\u00e9phone","og_description":"Un accessoire pratique et s\u00fbr qui maintient votre t\u00e9l\u00e9phone en place pendant la cartographie, ce qui facilite la visualisation de l&rsquo;itin\u00e9raire.","og_url":"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_9a3fc8cdb221c84ad6729414bb073c1b9665d977.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/","url":"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/","name":"Support pour t\u00e9l\u00e9phone | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_9a3fc8cdb221c84ad6729414bb073c1b9665d977.1980x.webp","datePublished":"2026-07-14T11:42:37+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_9a3fc8cdb221c84ad6729414bb073c1b9665d977.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_9a3fc8cdb221c84ad6729414bb073c1b9665d977.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-be\/support-pour-telephone-ka3027\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-be\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Support pour t\u00e9l\u00e9phone"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product\/1298988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/media\/555313"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/media?parent=1298988"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product_brand?post=1298988"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product_cat?post=1298988"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product_tag?post=1298988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}