{"id":1296388,"date":"2026-07-14T11:40:27","date_gmt":"2026-07-14T11:40:27","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844","status":"publish","type":"product","link":"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/","title":{"rendered":"Chargeur CyberLite DC-DC 60 V de qualit\u00e9 commerciale"},"content":{"rendered":"<p>Con\u00e7u pour les professionnels, le syst\u00e8me de charge DC-DC CyberTank Lite red\u00e9finit la portabilit\u00e9. Il est con\u00e7u pour transf\u00e9rer l&rsquo;\u00e9nergie d&rsquo;une CyberCapsule \u00e0 n&rsquo;importe quel CyberPack en seulement 12 minutes. Cette mobilit\u00e9 garantit que vos outils peuvent \u00eatre recharg\u00e9s rapidement et efficacement, ce qui vous permet de rester op\u00e9rationnel sans les contraintes d&rsquo;un lieu de chargement fixe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con\u00e7u pour les professionnels, le syst\u00e8me de charge DC-DC CyberTank Lite red\u00e9finit la portabilit\u00e9. Il est con\u00e7u pour transf\u00e9rer l&rsquo;\u00e9nergie d&rsquo;une CyberCapsule \u00e0 n&rsquo;importe quel CyberPack en seulement 12 minutes. Cette mobilit\u00e9 garantit que vos outils peuvent \u00eatre recharg\u00e9s rapidement et efficacement, ce qui vous permet de rester op\u00e9rationnel sans les contraintes d&rsquo;un lieu de [&hellip;]<\/p>\n","protected":false},"featured_media":410872,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[],"product_tag":[],"class_list":{"0":"post-1296388","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chargeur CyberLite DC-DC 60 V de qualit\u00e9 commerciale | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chargeur CyberLite DC-DC 60 V de qualit\u00e9 commerciale\" \/>\n<meta property=\"og:description\" content=\"Con\u00e7u pour les professionnels, le syst\u00e8me de charge DC-DC CyberTank Lite red\u00e9finit la portabilit\u00e9. Il est con\u00e7u pour transf\u00e9rer l&rsquo;\u00e9nergie d&rsquo;une CyberCapsule \u00e0 n&rsquo;importe quel CyberPack en seulement 12 minutes. Cette mobilit\u00e9 garantit que vos outils peuvent \u00eatre recharg\u00e9s rapidement et efficacement, ce qui vous permet de rester op\u00e9rationnel sans les contraintes d&rsquo;un lieu de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_1eb67f126aa6e30166b0358b4dee47dbe693f033.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\\\/\",\"name\":\"Chargeur CyberLite DC-DC 60 V de qualit\u00e9 commerciale | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_1eb67f126aa6e30166b0358b4dee47dbe693f033.1980x.webp\",\"datePublished\":\"2026-07-14T11:40:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_1eb67f126aa6e30166b0358b4dee47dbe693f033.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_1eb67f126aa6e30166b0358b4dee47dbe693f033.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chargeur CyberLite DC-DC 60 V de qualit\u00e9 commerciale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chargeur CyberLite DC-DC 60 V de qualit\u00e9 commerciale | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Chargeur CyberLite DC-DC 60 V de qualit\u00e9 commerciale","og_description":"Con\u00e7u pour les professionnels, le syst\u00e8me de charge DC-DC CyberTank Lite red\u00e9finit la portabilit\u00e9. Il est con\u00e7u pour transf\u00e9rer l&rsquo;\u00e9nergie d&rsquo;une CyberCapsule \u00e0 n&rsquo;importe quel CyberPack en seulement 12 minutes. Cette mobilit\u00e9 garantit que vos outils peuvent \u00eatre recharg\u00e9s rapidement et efficacement, ce qui vous permet de rester op\u00e9rationnel sans les contraintes d&rsquo;un lieu de [&hellip;]","og_url":"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_1eb67f126aa6e30166b0358b4dee47dbe693f033.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/","url":"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/","name":"Chargeur CyberLite DC-DC 60 V de qualit\u00e9 commerciale | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_1eb67f126aa6e30166b0358b4dee47dbe693f033.1980x.webp","datePublished":"2026-07-14T11:40:27+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_1eb67f126aa6e30166b0358b4dee47dbe693f033.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_1eb67f126aa6e30166b0358b4dee47dbe693f033.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/fr-be\/chargeur-cyberlite-dc-dc-60-v-de-qualite-commerciale-kac844\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/fr-be\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Chargeur CyberLite DC-DC 60 V de qualit\u00e9 commerciale"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product\/1296388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/media\/410872"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/media?parent=1296388"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product_brand?post=1296388"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product_cat?post=1296388"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/fr-be\/wp-json\/wp\/v2\/product_tag?post=1296388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}