{"id":1298237,"date":"2026-07-14T11:42:01","date_gmt":"2026-07-14T11:42:01","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es","status":"publish","type":"product","link":"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\/","title":{"rendered":"Cortac\u00e9sped rob\u00f3tico Kress EyePilot\u00ae RTK\u207f de 700 m\u00b2 con ZeroTrim y 4G integrado"},"content":{"rendered":"<p>El Kress EyePilot\u00ae RTKn KR260ES, que ofrece un cuidado del c\u00e9sped con la precisi\u00f3n de un campo de golf, combina el posicionamiento por sat\u00e9lite RTK con la percepci\u00f3n basada en la visi\u00f3n para desplazarse por entornos de jard\u00edn complejos, sin necesidad de hardware adicional.<\/p>\n<p>La correcci\u00f3n RTK se transmite de forma inal\u00e1mbrica, respaldada por una arquitectura de posicionamiento redundante que mantiene una localizaci\u00f3n precisa incluso cuando las se\u00f1ales de sat\u00e9lite se ven afectadas.<\/p>\n<p>El sistema de corte ZeroTrim corta con precisi\u00f3n hasta el borde, lo que reduce la necesidad de recortes posteriores, mientras que las trayectorias de corte estructuradas o aleatorias permiten obtener rayas n\u00edtidas o un acabado m\u00e1s natural.<\/p>\n<p>La conectividad se mantiene a trav\u00e9s de Wi-Fi o 4G integrado, lo que garantiza un funcionamiento fiable incluso cuando la cobertura inal\u00e1mbrica es limitada. Sin costes adicionales, se incluyen una tarjeta SIM integrada y un servicio de datos activo, por lo que EyePilot permanece conectado, actualizado y localizable en todo momento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Kress EyePilot\u00ae RTKn KR260ES, que ofrece un cuidado del c\u00e9sped con la precisi\u00f3n de un campo de golf, combina el posicionamiento por sat\u00e9lite RTK con la percepci\u00f3n basada en la visi\u00f3n para desplazarse por entornos de jard\u00edn complejos, sin necesidad de hardware adicional. La correcci\u00f3n RTK se transmite de forma inal\u00e1mbrica, respaldada por una [&hellip;]<\/p>\n","protected":false},"featured_media":522440,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52393],"product_tag":[],"class_list":{"0":"post-1298237","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-robots-cortacesped","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cortac\u00e9sped rob\u00f3tico Kress EyePilot\u00ae RTK\u207f de 700 m\u00b2 con ZeroTrim y 4G integrado | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cortac\u00e9sped rob\u00f3tico Kress EyePilot\u00ae RTK\u207f de 700 m\u00b2 con ZeroTrim y 4G integrado\" \/>\n<meta property=\"og:description\" content=\"El Kress EyePilot\u00ae RTKn KR260ES, que ofrece un cuidado del c\u00e9sped con la precisi\u00f3n de un campo de golf, combina el posicionamiento por sat\u00e9lite RTK con la percepci\u00f3n basada en la visi\u00f3n para desplazarse por entornos de jard\u00edn complejos, sin necesidad de hardware adicional. La correcci\u00f3n RTK se transmite de forma inal\u00e1mbrica, respaldada por una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk\u207f-de-700-m\u00b2-con-zerotrim-y-4g-integrado-kr260es\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\\\/\",\"name\":\"Cortac\u00e9sped rob\u00f3tico Kress EyePilot\u00ae RTK\u207f de 700 m\u00b2 con ZeroTrim y 4G integrado | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp\",\"datePublished\":\"2026-07-14T11:42:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\\\/#breadcrumb\"},\"inLanguage\":\"es-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-US\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cortac\u00e9sped rob\u00f3tico Kress EyePilot\u00ae RTK\u207f de 700 m\u00b2 con ZeroTrim y 4G integrado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-US\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cortac\u00e9sped rob\u00f3tico Kress EyePilot\u00ae RTK\u207f de 700 m\u00b2 con ZeroTrim y 4G integrado | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Cortac\u00e9sped rob\u00f3tico Kress EyePilot\u00ae RTK\u207f de 700 m\u00b2 con ZeroTrim y 4G integrado","og_description":"El Kress EyePilot\u00ae RTKn KR260ES, que ofrece un cuidado del c\u00e9sped con la precisi\u00f3n de un campo de golf, combina el posicionamiento por sat\u00e9lite RTK con la percepci\u00f3n basada en la visi\u00f3n para desplazarse por entornos de jard\u00edn complejos, sin necesidad de hardware adicional. La correcci\u00f3n RTK se transmite de forma inal\u00e1mbrica, respaldada por una [&hellip;]","og_url":"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk\u207f-de-700-m\u00b2-con-zerotrim-y-4g-integrado-kr260es\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\/","url":"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\/","name":"Cortac\u00e9sped rob\u00f3tico Kress EyePilot\u00ae RTK\u207f de 700 m\u00b2 con ZeroTrim y 4G integrado | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp","datePublished":"2026-07-14T11:42:01+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\/#breadcrumb"},"inLanguage":"es-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\/"]}]},{"@type":"ImageObject","inLanguage":"es-US","@id":"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_39f91e622447499497d8df62a39de706a3c07b62.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/es-us\/cortacesped-robotico-kress-eyepilot-rtk%e2%81%bf-de-700-m%c2%b2-con-zerotrim-y-4g-integrado-kr260es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/es-us\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Cortac\u00e9sped rob\u00f3tico Kress EyePilot\u00ae RTK\u207f de 700 m\u00b2 con ZeroTrim y 4G integrado"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-US"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"es-US","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product\/1298237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/media\/522440"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/media?parent=1298237"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product_brand?post=1298237"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product_cat?post=1298237"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product_tag?post=1298237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}