{"id":1297145,"date":"2026-07-14T11:41:04","date_gmt":"2026-07-14T11:41:04","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"cuchilla-segadora-de-47-cm-kac708","status":"publish","type":"product","link":"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/","title":{"rendered":"cuchilla segadora de 47 cm"},"content":{"rendered":"<p>Compatible con: KC720<\/p>\n<p>cuchilla cortac\u00e9sped de 47 cm de altura para un mayor rendimiento de ensacado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compatible con: KC720 cuchilla cortac\u00e9sped de 47 cm de altura para un mayor rendimiento de ensacado<\/p>\n","protected":false},"featured_media":411280,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52574],"product_tag":[],"class_list":{"0":"post-1297145","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios-para-cortacespedes","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>cuchilla segadora de 47 cm | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cuchilla segadora de 47 cm\" \/>\n<meta property=\"og:description\" content=\"Compatible con: KC720 cuchilla cortac\u00e9sped de 47 cm de altura para un mayor rendimiento de ensacado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b4189cca5acebe2824e69296e647c3bdf6b24ca.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cuchilla-segadora-de-47-cm-kac708\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cuchilla-segadora-de-47-cm-kac708\\\/\",\"name\":\"cuchilla segadora de 47 cm | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cuchilla-segadora-de-47-cm-kac708\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cuchilla-segadora-de-47-cm-kac708\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_4b4189cca5acebe2824e69296e647c3bdf6b24ca.1980x.webp\",\"datePublished\":\"2026-07-14T11:41:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cuchilla-segadora-de-47-cm-kac708\\\/#breadcrumb\"},\"inLanguage\":\"es-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cuchilla-segadora-de-47-cm-kac708\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-US\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cuchilla-segadora-de-47-cm-kac708\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_4b4189cca5acebe2824e69296e647c3bdf6b24ca.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_4b4189cca5acebe2824e69296e647c3bdf6b24ca.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/cuchilla-segadora-de-47-cm-kac708\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"cuchilla segadora de 47 cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-US\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"cuchilla segadora de 47 cm | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"cuchilla segadora de 47 cm","og_description":"Compatible con: KC720 cuchilla cortac\u00e9sped de 47 cm de altura para un mayor rendimiento de ensacado","og_url":"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b4189cca5acebe2824e69296e647c3bdf6b24ca.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/","url":"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/","name":"cuchilla segadora de 47 cm | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b4189cca5acebe2824e69296e647c3bdf6b24ca.1980x.webp","datePublished":"2026-07-14T11:41:04+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/#breadcrumb"},"inLanguage":"es-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/"]}]},{"@type":"ImageObject","inLanguage":"es-US","@id":"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b4189cca5acebe2824e69296e647c3bdf6b24ca.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_4b4189cca5acebe2824e69296e647c3bdf6b24ca.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/es-us\/cuchilla-segadora-de-47-cm-kac708\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/es-us\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"cuchilla segadora de 47 cm"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-US"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"es-US","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product\/1297145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/media\/411280"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/media?parent=1297145"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product_brand?post=1297145"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product_cat?post=1297145"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product_tag?post=1297145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}