{"id":1293921,"date":"2026-07-14T11:38:34","date_gmt":"2026-07-14T11:38:34","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"accesorio-cortasetos-profesional-kress-ka0420","status":"publish","type":"product","link":"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/","title":{"rendered":"Accesorio cortasetos profesional Kress"},"content":{"rendered":"<p>Compatible con KG163.9. Este accesorio cortasetos est\u00e1 dise\u00f1ado para cortar setos y arbustos dif\u00edciles con facilidad. Con un rendimiento y una flexibilidad de nivel profesional, garantiza un mantenimiento impecable de sus setos, \u00e1rboles y arbustos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compatible con KG163.9. Este accesorio cortasetos est\u00e1 dise\u00f1ado para cortar setos y arbustos dif\u00edciles con facilidad. Con un rendimiento y una flexibilidad de nivel profesional, garantiza un mantenimiento impecable de sus setos, \u00e1rboles y arbustos.<\/p>\n","protected":false},"featured_media":409312,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52652],"product_tag":[],"class_list":{"0":"post-1293921","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios-para-cortasetos","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Accesorio cortasetos profesional Kress | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accesorio cortasetos profesional Kress\" \/>\n<meta property=\"og:description\" content=\"Compatible con KG163.9. Este accesorio cortasetos est\u00e1 dise\u00f1ado para cortar setos y arbustos dif\u00edciles con facilidad. Con un rendimiento y una flexibilidad de nivel profesional, garantiza un mantenimiento impecable de sus setos, \u00e1rboles y arbustos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_993cfa9fca9b8f757f866b4249e3b82bf64c1f91.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/accesorio-cortasetos-profesional-kress-ka0420\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/accesorio-cortasetos-profesional-kress-ka0420\\\/\",\"name\":\"Accesorio cortasetos profesional Kress | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/accesorio-cortasetos-profesional-kress-ka0420\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/accesorio-cortasetos-profesional-kress-ka0420\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_993cfa9fca9b8f757f866b4249e3b82bf64c1f91.1980x.webp\",\"datePublished\":\"2026-07-14T11:38:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/accesorio-cortasetos-profesional-kress-ka0420\\\/#breadcrumb\"},\"inLanguage\":\"es-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/es-us\\\/accesorio-cortasetos-profesional-kress-ka0420\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-US\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/accesorio-cortasetos-profesional-kress-ka0420\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_993cfa9fca9b8f757f866b4249e3b82bf64c1f91.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_993cfa9fca9b8f757f866b4249e3b82bf64c1f91.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/accesorio-cortasetos-profesional-kress-ka0420\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/es-us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Accesorio cortasetos profesional Kress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-US\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Accesorio cortasetos profesional Kress | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Accesorio cortasetos profesional Kress","og_description":"Compatible con KG163.9. Este accesorio cortasetos est\u00e1 dise\u00f1ado para cortar setos y arbustos dif\u00edciles con facilidad. Con un rendimiento y una flexibilidad de nivel profesional, garantiza un mantenimiento impecable de sus setos, \u00e1rboles y arbustos.","og_url":"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_993cfa9fca9b8f757f866b4249e3b82bf64c1f91.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/","url":"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/","name":"Accesorio cortasetos profesional Kress | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_993cfa9fca9b8f757f866b4249e3b82bf64c1f91.1980x.webp","datePublished":"2026-07-14T11:38:34+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/#breadcrumb"},"inLanguage":"es-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/"]}]},{"@type":"ImageObject","inLanguage":"es-US","@id":"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_993cfa9fca9b8f757f866b4249e3b82bf64c1f91.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_993cfa9fca9b8f757f866b4249e3b82bf64c1f91.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/es-us\/accesorio-cortasetos-profesional-kress-ka0420\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/es-us\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Accesorio cortasetos profesional Kress"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-US"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"es-US","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product\/1293921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/media\/409312"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/media?parent=1293921"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product_brand?post=1293921"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product_cat?post=1293921"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/es-us\/wp-json\/wp\/v2\/product_tag?post=1293921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}