{"id":1295942,"date":"2026-07-14T11:40:01","date_gmt":"2026-07-14T11:40:01","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"cortabordes-de-60-v-para-uso-comercial-kc110-9","status":"publish","type":"product","link":"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/","title":{"rendered":"Cortabordes de 60 V para uso comercial"},"content":{"rendered":"<p>Dise\u00f1ada para empresas de jardiner\u00eda y municipios que buscan integrar pr\u00e1cticas sostenibles en sus operaciones, la recortadora de hilo Kress KC110 destaca por su motor delantero estrat\u00e9gicamente situado, que mejora el equilibrio y la maniobrabilidad para trabajos de jardiner\u00eda de precisi\u00f3n. Con una robusta potencia de 0,9 kW que rivaliza con un motor de gasolina de 31 cc, la recortadora de hilo Kress, con s\u00f3lo 3 kg de peso, garantiza un f\u00e1cil manejo y reduce la fatiga. Como parte del Kress Commercial CyberSystem, ofrece un rendimiento de alta gama con la ventaja de unos costes de funcionamiento m\u00e1s bajos en comparaci\u00f3n con los sistemas de gasolina y otros sistemas de bater\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dise\u00f1ada para empresas de jardiner\u00eda y municipios que buscan integrar pr\u00e1cticas sostenibles en sus operaciones, la recortadora de hilo Kress KC110 destaca por su motor delantero estrat\u00e9gicamente situado, que mejora el equilibrio y la maniobrabilidad para trabajos de jardiner\u00eda de precisi\u00f3n. Con una robusta potencia de 0,9 kW que rivaliza con un motor de gasolina [&hellip;]<\/p>\n","protected":false},"featured_media":410512,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52801],"product_tag":[],"class_list":{"0":"post-1295942","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cortabordes","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cortabordes de 60 V para uso comercial | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cortabordes de 60 V para uso comercial\" \/>\n<meta property=\"og:description\" content=\"Dise\u00f1ada para empresas de jardiner\u00eda y municipios que buscan integrar pr\u00e1cticas sostenibles en sus operaciones, la recortadora de hilo Kress KC110 destaca por su motor delantero estrat\u00e9gicamente situado, que mejora el equilibrio y la maniobrabilidad para trabajos de jardiner\u00eda de precisi\u00f3n. Con una robusta potencia de 0,9 kW que rivaliza con un motor de gasolina [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c87435c3828216f8ad999f73a61aca02a9f968c6.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-es\\\/cortabordes-de-60-v-para-uso-comercial-kc110-9\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/es-es\\\/cortabordes-de-60-v-para-uso-comercial-kc110-9\\\/\",\"name\":\"Cortabordes de 60 V para uso comercial | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-es\\\/cortabordes-de-60-v-para-uso-comercial-kc110-9\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-es\\\/cortabordes-de-60-v-para-uso-comercial-kc110-9\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_c87435c3828216f8ad999f73a61aca02a9f968c6.1980x.webp\",\"datePublished\":\"2026-07-14T11:40:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-es\\\/cortabordes-de-60-v-para-uso-comercial-kc110-9\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/es-es\\\/cortabordes-de-60-v-para-uso-comercial-kc110-9\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-es\\\/cortabordes-de-60-v-para-uso-comercial-kc110-9\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_c87435c3828216f8ad999f73a61aca02a9f968c6.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_c87435c3828216f8ad999f73a61aca02a9f968c6.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/es-es\\\/cortabordes-de-60-v-para-uso-comercial-kc110-9\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/es-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cortabordes de 60 V para uso comercial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cortabordes de 60 V para uso comercial | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Cortabordes de 60 V para uso comercial","og_description":"Dise\u00f1ada para empresas de jardiner\u00eda y municipios que buscan integrar pr\u00e1cticas sostenibles en sus operaciones, la recortadora de hilo Kress KC110 destaca por su motor delantero estrat\u00e9gicamente situado, que mejora el equilibrio y la maniobrabilidad para trabajos de jardiner\u00eda de precisi\u00f3n. Con una robusta potencia de 0,9 kW que rivaliza con un motor de gasolina [&hellip;]","og_url":"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c87435c3828216f8ad999f73a61aca02a9f968c6.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/","url":"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/","name":"Cortabordes de 60 V para uso comercial | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c87435c3828216f8ad999f73a61aca02a9f968c6.1980x.webp","datePublished":"2026-07-14T11:40:01+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c87435c3828216f8ad999f73a61aca02a9f968c6.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_c87435c3828216f8ad999f73a61aca02a9f968c6.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/es-es\/cortabordes-de-60-v-para-uso-comercial-kc110-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Cortabordes de 60 V para uso comercial"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/es-es\/wp-json\/wp\/v2\/product\/1295942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/es-es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/es-es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/es-es\/wp-json\/wp\/v2\/media\/410512"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/es-es\/wp-json\/wp\/v2\/media?parent=1295942"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/es-es\/wp-json\/wp\/v2\/product_brand?post=1295942"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/es-es\/wp-json\/wp\/v2\/product_cat?post=1295942"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/es-es\/wp-json\/wp\/v2\/product_tag?post=1295942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}