{"id":1292226,"date":"2026-07-14T11:37:25","date_gmt":"2026-07-14T11:37:25","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"off-road-wheels-ka0221","status":"publish","type":"product","link":"https:\/\/www.kress.com\/en-us\/off-road-wheels-ka0221\/","title":{"rendered":"Off-road wheels"},"content":{"rendered":"<p>Compatible with: KR120E, KR121E, KR122E, KR123E. <\/p>\n<p>Improves climbing ability by 30% and skid resistance by 30%, making it more suitable for uneven lawns.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compatible with: KR120E, KR121E, KR122E, KR123E. Improves climbing ability by 30% and skid resistance by 30%, making it more suitable for uneven lawns.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52465],"product_tag":[],"class_list":{"0":"post-1292226","1":"product","2":"type-product","3":"status-publish","5":"product_cat-accessories-for-robotic-mowers","7":"first","8":"instock","9":"shipping-taxable","10":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Off-road wheels | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Off-road wheels\" \/>\n<meta property=\"og:description\" content=\"Compatible with: KR120E, KR121E, KR122E, KR123E. Improves climbing ability by 30% and skid resistance by 30%, making it more suitable for uneven lawns.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/en-us\/off-road-wheels-ka0221\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_6a2fd0e8e14583c31ae018c36da9a0216b8e9ca1.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/en-us\\\/off-road-wheels-ka0221\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/en-us\\\/off-road-wheels-ka0221\\\/\",\"name\":\"Off-road wheels | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"datePublished\":\"2026-07-14T11:37:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/en-us\\\/off-road-wheels-ka0221\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/en-us\\\/off-road-wheels-ka0221\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/en-us\\\/off-road-wheels-ka0221\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/en-us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Off-road wheels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Off-road wheels | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Off-road wheels","og_description":"Compatible with: KR120E, KR121E, KR122E, KR123E. Improves climbing ability by 30% and skid resistance by 30%, making it more suitable for uneven lawns.","og_url":"https:\/\/www.kress.com\/en-us\/off-road-wheels-ka0221\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_6a2fd0e8e14583c31ae018c36da9a0216b8e9ca1.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/en-us\/off-road-wheels-ka0221\/","url":"https:\/\/www.kress.com\/en-us\/off-road-wheels-ka0221\/","name":"Off-road wheels | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"datePublished":"2026-07-14T11:37:25+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/en-us\/off-road-wheels-ka0221\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/en-us\/off-road-wheels-ka0221\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/en-us\/off-road-wheels-ka0221\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/en-us\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Off-road wheels"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/en-us\/wp-json\/wp\/v2\/product\/1292226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/en-us\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/en-us\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/en-us\/wp-json\/wp\/v2\/media?parent=1292226"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/en-us\/wp-json\/wp\/v2\/product_brand?post=1292226"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/en-us\/wp-json\/wp\/v2\/product_cat?post=1292226"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/en-us\/wp-json\/wp\/v2\/product_tag?post=1292226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}