{"id":1295085,"date":"2026-07-14T11:39:23","date_gmt":"2026-07-14T11:39:23","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"30-cm-knife-blade-kac170","status":"publish","type":"product","link":"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/","title":{"rendered":"30 cm Knife blade"},"content":{"rendered":"<p>Compatible with: KC100\/KC120\/KC170<\/p>\n<p>30 cm tri-bladed brush-cutting attachment for usage on heavy vegetation, reeds, and bushes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compatible with: KC100\/KC120\/KC170 30 cm tri-bladed brush-cutting attachment for usage on heavy vegetation, reeds, and bushes.<\/p>\n","protected":false},"featured_media":409984,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52594],"product_tag":[],"class_list":{"0":"post-1295085","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessories-for-grass-trimmers","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>30 cm Knife blade | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"30 cm Knife blade\" \/>\n<meta property=\"og:description\" content=\"Compatible with: KC100\/KC120\/KC170 30 cm tri-bladed brush-cutting attachment for usage on heavy vegetation, reeds, and bushes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_7ad09b0cdc2319a777880c5427c15ba6083b9071.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/en-ca\\\/30-cm-knife-blade-kac170\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/en-ca\\\/30-cm-knife-blade-kac170\\\/\",\"name\":\"30 cm Knife blade | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/en-ca\\\/30-cm-knife-blade-kac170\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/en-ca\\\/30-cm-knife-blade-kac170\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_7ad09b0cdc2319a777880c5427c15ba6083b9071.1980x.webp\",\"datePublished\":\"2026-07-14T11:39:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/en-ca\\\/30-cm-knife-blade-kac170\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/en-ca\\\/30-cm-knife-blade-kac170\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/en-ca\\\/30-cm-knife-blade-kac170\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_7ad09b0cdc2319a777880c5427c15ba6083b9071.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_7ad09b0cdc2319a777880c5427c15ba6083b9071.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/en-ca\\\/30-cm-knife-blade-kac170\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/en-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"30 cm Knife blade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"30 cm Knife blade | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"30 cm Knife blade","og_description":"Compatible with: KC100\/KC120\/KC170 30 cm tri-bladed brush-cutting attachment for usage on heavy vegetation, reeds, and bushes.","og_url":"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_7ad09b0cdc2319a777880c5427c15ba6083b9071.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/","url":"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/","name":"30 cm Knife blade | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_7ad09b0cdc2319a777880c5427c15ba6083b9071.1980x.webp","datePublished":"2026-07-14T11:39:23+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_7ad09b0cdc2319a777880c5427c15ba6083b9071.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_7ad09b0cdc2319a777880c5427c15ba6083b9071.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/en-ca\/30-cm-knife-blade-kac170\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/en-ca\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"30 cm Knife blade"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/en-ca\/wp-json\/wp\/v2\/product\/1295085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/en-ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/en-ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/en-ca\/wp-json\/wp\/v2\/media\/409984"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/en-ca\/wp-json\/wp\/v2\/media?parent=1295085"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/en-ca\/wp-json\/wp\/v2\/product_brand?post=1295085"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/en-ca\/wp-json\/wp\/v2\/product_cat?post=1295085"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/en-ca\/wp-json\/wp\/v2\/product_tag?post=1295085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}