{"id":1298973,"date":"2026-07-14T11:42:36","date_gmt":"2026-07-14T11:42:36","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"auslassblende-ka0800","status":"publish","type":"product","link":"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/","title":{"rendered":"Auslassblende"},"content":{"rendered":"<p>Ein praktischer Aufsatz, der das Schnittgut effizient ableitet und so f\u00fcr einen gleichm\u00e4\u00dfigen Auswurf und einen saubereren Betrieb sorgt<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein praktischer Aufsatz, der das Schnittgut effizient ableitet und so f\u00fcr einen gleichm\u00e4\u00dfigen Auswurf und einen saubereren Betrieb sorgt<\/p>\n","protected":false},"featured_media":551142,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52478],"product_tag":[],"class_list":{"0":"post-1298973","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zubehoer-fuer-maehroboter","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Auslassblende | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auslassblende\" \/>\n<meta property=\"og:description\" content=\"Ein praktischer Aufsatz, der das Schnittgut effizient ableitet und so f\u00fcr einen gleichm\u00e4\u00dfigen Auswurf und einen saubereren Betrieb sorgt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_99d7aaca86f2fdead4d7076b3f493c727090c12e.1980x.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-lu\\\/auslassblende-ka0800\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-lu\\\/auslassblende-ka0800\\\/\",\"name\":\"Auslassblende | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-lu\\\/auslassblende-ka0800\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-lu\\\/auslassblende-ka0800\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_99d7aaca86f2fdead4d7076b3f493c727090c12e.1980x.webp\",\"datePublished\":\"2026-07-14T11:42:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-lu\\\/auslassblende-ka0800\\\/#breadcrumb\"},\"inLanguage\":\"de-LU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/de-lu\\\/auslassblende-ka0800\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-LU\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-lu\\\/auslassblende-ka0800\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_99d7aaca86f2fdead4d7076b3f493c727090c12e.1980x.webp\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/onpage\\\/op_image_99d7aaca86f2fdead4d7076b3f493c727090c12e.1980x.webp\",\"width\":1980,\"height\":1980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-lu\\\/auslassblende-ka0800\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/de-lu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Auslassblende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-LU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-LU\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Auslassblende | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Auslassblende","og_description":"Ein praktischer Aufsatz, der das Schnittgut effizient ableitet und so f\u00fcr einen gleichm\u00e4\u00dfigen Auswurf und einen saubereren Betrieb sorgt","og_url":"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/","og_site_name":"Kress","og_image":[{"width":1980,"height":1980,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_99d7aaca86f2fdead4d7076b3f493c727090c12e.1980x.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/","url":"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/","name":"Auslassblende | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/#primaryimage"},"image":{"@id":"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_99d7aaca86f2fdead4d7076b3f493c727090c12e.1980x.webp","datePublished":"2026-07-14T11:42:36+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/#breadcrumb"},"inLanguage":"de-LU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/"]}]},{"@type":"ImageObject","inLanguage":"de-LU","@id":"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/#primaryimage","url":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_99d7aaca86f2fdead4d7076b3f493c727090c12e.1980x.webp","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/onpage\/op_image_99d7aaca86f2fdead4d7076b3f493c727090c12e.1980x.webp","width":1980,"height":1980},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/de-lu\/auslassblende-ka0800\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/de-lu\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Auslassblende"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-LU"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"de-LU","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/de-lu\/wp-json\/wp\/v2\/product\/1298973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/de-lu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/de-lu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kress.com\/de-lu\/wp-json\/wp\/v2\/media\/551142"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/de-lu\/wp-json\/wp\/v2\/media?parent=1298973"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/de-lu\/wp-json\/wp\/v2\/product_brand?post=1298973"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/de-lu\/wp-json\/wp\/v2\/product_cat?post=1298973"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/de-lu\/wp-json\/wp\/v2\/product_tag?post=1298973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}