{"id":1292443,"date":"2026-07-14T11:37:36","date_gmt":"2026-07-14T11:37:36","guid":{"rendered":""},"modified":"2026-07-14T11:36:43","modified_gmt":"2026-07-14T11:36:43","slug":"handelsuebliches-rucksack-batteriegeschirr-kac900","status":"publish","type":"product","link":"https:\/\/www.kress.com\/de-at\/handelsuebliches-rucksack-batteriegeschirr-kac900\/","title":{"rendered":"Handels\u00fcbliches Rucksack-Batteriegeschirr"},"content":{"rendered":"<p>Der Kress Commercial 60 V Rucksack-Akku-Gurt verbindet ergonomisches Design mit praktischer Handhabung. Er l\u00e4sst sich in der H\u00f6he verstellen und ist mit allen Werkzeugen kompatibel. Seine Konstruktion ist darauf ausgerichtet, das Gewicht gleichm\u00e4\u00dfig zu verteilen, um Erm\u00fcdungserscheinungen bei langen Arbeitszeiten zu verringern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Kress Commercial 60 V Rucksack-Akku-Gurt verbindet ergonomisches Design mit praktischer Handhabung. Er l\u00e4sst sich in der H\u00f6he verstellen und ist mit allen Werkzeugen kompatibel. Seine Konstruktion ist darauf ausgerichtet, das Gewicht gleichm\u00e4\u00dfig zu verteilen, um Erm\u00fcdungserscheinungen bei langen Arbeitszeiten zu verringern.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[52838],"product_tag":[],"class_list":{"0":"post-1292443","1":"product","2":"type-product","3":"status-publish","5":"product_cat-zubehoer-fuer-batterien-und-ladegeraete","7":"first","8":"instock","9":"shipping-taxable","10":"purchasable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Handels\u00fcbliches Rucksack-Batteriegeschirr | Kress<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Handels\u00fcbliches Rucksack-Batteriegeschirr\" \/>\n<meta property=\"og:description\" content=\"Der Kress Commercial 60 V Rucksack-Akku-Gurt verbindet ergonomisches Design mit praktischer Handhabung. Er l\u00e4sst sich in der H\u00f6he verstellen und ist mit allen Werkzeugen kompatibel. Seine Konstruktion ist darauf ausgerichtet, das Gewicht gleichm\u00e4\u00dfig zu verteilen, um Erm\u00fcdungserscheinungen bei langen Arbeitszeiten zu verringern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kress.com\/de-at\/handelsuebliches-rucksack-batteriegeschirr-kac900\/\" \/>\n<meta property=\"og:site_name\" content=\"Kress\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"43\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-at\\\/handelsuebliches-rucksack-batteriegeschirr-kac900\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-at\\\/handelsuebliches-rucksack-batteriegeschirr-kac900\\\/\",\"name\":\"Handels\u00fcbliches Rucksack-Batteriegeschirr | Kress\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\"},\"datePublished\":\"2026-07-14T11:37:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-at\\\/handelsuebliches-rucksack-batteriegeschirr-kac900\\\/#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kress.com\\\/de-at\\\/handelsuebliches-rucksack-batteriegeschirr-kac900\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-at\\\/handelsuebliches-rucksack-batteriegeschirr-kac900\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kress.com\\\/de-at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.kress.com\\\/fr-fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Handels\u00fcbliches Rucksack-Batteriegeschirr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"name\":\"Kress\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#organization\",\"name\":\"Kress\",\"url\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.kress.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-kress_logo@2x.png\",\"width\":185,\"height\":43,\"caption\":\"Kress\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kress.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Handels\u00fcbliches Rucksack-Batteriegeschirr | Kress","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Handels\u00fcbliches Rucksack-Batteriegeschirr","og_description":"Der Kress Commercial 60 V Rucksack-Akku-Gurt verbindet ergonomisches Design mit praktischer Handhabung. Er l\u00e4sst sich in der H\u00f6he verstellen und ist mit allen Werkzeugen kompatibel. Seine Konstruktion ist darauf ausgerichtet, das Gewicht gleichm\u00e4\u00dfig zu verteilen, um Erm\u00fcdungserscheinungen bei langen Arbeitszeiten zu verringern.","og_url":"https:\/\/www.kress.com\/de-at\/handelsuebliches-rucksack-batteriegeschirr-kac900\/","og_site_name":"Kress","og_image":[{"width":185,"height":43,"url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.kress.com\/de-at\/handelsuebliches-rucksack-batteriegeschirr-kac900\/","url":"https:\/\/www.kress.com\/de-at\/handelsuebliches-rucksack-batteriegeschirr-kac900\/","name":"Handels\u00fcbliches Rucksack-Batteriegeschirr | Kress","isPartOf":{"@id":"https:\/\/www.kress.com\/de-de\/#website"},"datePublished":"2026-07-14T11:37:36+00:00","breadcrumb":{"@id":"https:\/\/www.kress.com\/de-at\/handelsuebliches-rucksack-batteriegeschirr-kac900\/#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kress.com\/de-at\/handelsuebliches-rucksack-batteriegeschirr-kac900\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kress.com\/de-at\/handelsuebliches-rucksack-batteriegeschirr-kac900\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kress.com\/de-at\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.kress.com\/fr-fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Handels\u00fcbliches Rucksack-Batteriegeschirr"}]},{"@type":"WebSite","@id":"https:\/\/www.kress.com\/de-de\/#website","url":"https:\/\/www.kress.com\/de-de\/","name":"Kress","description":"","publisher":{"@id":"https:\/\/www.kress.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kress.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-AT"},{"@type":"Organization","@id":"https:\/\/www.kress.com\/de-de\/#organization","name":"Kress","url":"https:\/\/www.kress.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","contentUrl":"https:\/\/www.kress.com\/wp-content\/uploads\/2024\/02\/cropped-kress_logo@2x.png","width":185,"height":43,"caption":"Kress"},"image":{"@id":"https:\/\/www.kress.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.kress.com\/de-at\/wp-json\/wp\/v2\/product\/1292443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kress.com\/de-at\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.kress.com\/de-at\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.kress.com\/de-at\/wp-json\/wp\/v2\/media?parent=1292443"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.kress.com\/de-at\/wp-json\/wp\/v2\/product_brand?post=1292443"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.kress.com\/de-at\/wp-json\/wp\/v2\/product_cat?post=1292443"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.kress.com\/de-at\/wp-json\/wp\/v2\/product_tag?post=1292443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}